{"id":2244650,"date":"2022-12-16T14:36:13","date_gmt":"2022-12-16T14:36:13","guid":{"rendered":"https:\/\/teguar.com\/eu\/teguar-mitarbeiter-verbreiten-weihnachtsstimmung-durch-ehrenamtliche-arbeit\/"},"modified":"2025-11-06T19:11:11","modified_gmt":"2025-11-06T19:11:11","slug":"teguar-mitarbeiter-verbreiten-weihnachtsstimmung-durch-ehrenamtliche-arbeit","status":"publish","type":"post","link":"https:\/\/teguar.com\/eu\/de\/teguar-mitarbeiter-verbreiten-weihnachtsstimmung-durch-ehrenamtliche-arbeit\/","title":{"rendered":"Teguar-Mitarbeiter verbreiten Weihnachtsstimmung durch ehrenamtliche Arbeit"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2022\/12\/HopeMatch-Volunteers-1-1024x808.jpg\" alt=\"\" class=\"wp-image-1902137\"\/><\/figure>\n\n<p class=\"wp-block-paragraph\">HOPEMatch wurde 2010 gegr\u00fcndet und ist eine Organisation, die sich um diejenigen k\u00fcmmert, die in unserer Gemeinschaft \u00fcbersehen werden. Urspr\u00fcnglich handelte es sich um ein weihnachtliches Programm, bei dem Spender mit bed\u00fcrftigen Familien zusammengebracht wurden, um sie mit Dingen auf ihrer Wunschliste im Wert von bis zu 200 Dollar pro Person zu versorgen. Inzwischen ist HOPEMatch zu einer Organisation herangewachsen, die das ganze Jahr \u00fcber verschiedene M\u00f6glichkeiten der Hilfe anbietet, wie z.B. Zugang zu Finanzkursen, lebensnotwendigen Gegenst\u00e4nden, Unterst\u00fctzung bei Feierlichkeiten und mehr.  <\/p>\n\n<p class=\"wp-block-paragraph\">Eine besondere M\u00f6glichkeit der Freiwilligenarbeit bei HOPEMatch ist das Geschenkverpackungsprogramm. Bei diesem Programm werden Freiwilligengruppen einer bed\u00fcrftigen Familie zugewiesen, f\u00fcr die sie Geschenke einpacken. Der Freiwillige erf\u00e4hrt dann ein wenig mehr \u00fcber die Situation der zugewiesenen Familie und schreibt pers\u00f6nliche Geschenkanh\u00e4nger auf jedes Geschenk. Eine Sache, die den HOPEMatch-Mitarbeitern wichtig ist, ist, dass die Freiwilligen jedes einzelne Geschenk einpacken &#8211; es werden keine Geschenkt\u00fcten verwendet. Das macht es f\u00fcr die Familie, die die Geschenke erh\u00e4lt, noch sch\u00f6ner!    <\/p>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2022\/12\/HopeMatch-Individual-Volunteers-1024x731.jpg\" alt=\"\" class=\"wp-image-1902138\"\/><\/figure>\n\n<p class=\"wp-block-paragraph\">Jedes Jahr zur Weihnachtszeit f\u00fchlen sich die Mitarbeiter von Teguar verpflichtet, der Gemeinschaft etwas zur\u00fcckzugeben. In den letzten Jahren haben sich mehrere Mitarbeiter freiwillig gemeldet, um an dem Geschenkverpackungsprogramm von HOPEMatch teilzunehmen. Kathleen Horwitt, Personalassistentin und diesj\u00e4hrige Leiterin der HOPEMatch-Initiative, berichtet von ihren Erfahrungen: &#8222;Ich denke, die HOPEmatch-Geschenkverpackungsaktion war ein gro\u00dfer Erfolg. Wir hatten 23 Mitarbeiter, die sich freiwillig gemeldet haben, und einen Mitarbeiter, der sogar an beiden Veranstaltungen teilgenommen hat. Ich war beeindruckt von den Leuten, die HOPEmatch leiten, denn die Veranstaltung war sehr gut organisiert. Ich finde es toll, dass so viele unserer Mitarbeiter bereit sind, ihre Zeit in den Dienst der Gemeinschaft zu stellen. Das Engagement von Teguar f\u00fcr unsere lokale Gemeinschaft ist beeindruckend. Vor allem, wie sie ihre Mitarbeiter ermutigen, sich zu engagieren, indem sie ihnen 8 Stunden pro Jahr f\u00fcr ehrenamtliche Arbeit bezahlen.&#8220;  <\/p>\n\n<p class=\"wp-block-paragraph\">Freiwilligenarbeit ist ein wichtiger Teil der Werte von Teguar, und HOPEMatch war \u00fcber die Jahre hinweg ein gro\u00dfartiger Partner. Wir hoffen, dass wir noch viele weitere Feiertage mit ihnen zusammenarbeiten k\u00f6nnen! <\/p>\n","protected":false},"excerpt":{"rendered":"<p>HOPEMatch wurde 2010 gegr\u00fcndet und ist eine Organisation, die sich um diejenigen k\u00fcmmert, die in unserer Gemeinschaft \u00fcbersehen werden. Urspr\u00fcnglich handelte es sich um ein weihnachtliches Programm, bei dem Spender mit bed\u00fcrftigen Familien zusammengebracht wurden, um sie mit Dingen auf ihrer Wunschliste im Wert von bis zu 200 Dollar pro Person zu versorgen. Inzwischen ist [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2285],"tags":[2387],"class_list":["post-2244650","post","type-post","status-publish","format-standard","hentry","category-news","tag-teguar-us-hq"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Teguar-Mitarbeiter verbreiten Weihnachtsstimmung durch ehrenamtliche Arbeit<\/title>\n<meta name=\"description\" content=\"Teguar kehrte im Dezember 2022 zu HOPEMatch zur\u00fcck und verpackte Weihnachtsgeschenke f\u00fcr Familien in der Gegend von Charlotte.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/teguar.com\/eu\/de\/teguar-mitarbeiter-verbreiten-weihnachtsstimmung-durch-ehrenamtliche-arbeit\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Teguar-Mitarbeiter verbreiten Weihnachtsstimmung durch ehrenamtliche Arbeit\" \/>\n<meta property=\"og:description\" content=\"Teguar kehrte im Dezember 2022 zu HOPEMatch zur\u00fcck und verpackte Weihnachtsgeschenke f\u00fcr Familien in der Gegend von Charlotte.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/teguar.com\/eu\/de\/teguar-mitarbeiter-verbreiten-weihnachtsstimmung-durch-ehrenamtliche-arbeit\/\" \/>\n<meta property=\"og:site_name\" content=\"Teguar\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-16T14:36:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-06T19:11:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2022\/12\/HopeMatch-Volunteers-1-1024x808.jpg\" \/>\n<meta name=\"author\" content=\"Emily Vrettos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Emily Vrettos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/teguar.com\\\/eu\\\/de\\\/teguar-mitarbeiter-verbreiten-weihnachtsstimmung-durch-ehrenamtliche-arbeit\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/teguar.com\\\/eu\\\/de\\\/teguar-mitarbeiter-verbreiten-weihnachtsstimmung-durch-ehrenamtliche-arbeit\\\/\"},\"author\":{\"name\":\"Emily Vrettos\",\"@id\":\"https:\\\/\\\/teguar.com\\\/eu\\\/en\\\/#\\\/schema\\\/person\\\/919e24265800376463d11889f0a5e3d0\"},\"headline\":\"Teguar-Mitarbeiter verbreiten Weihnachtsstimmung durch ehrenamtliche Arbeit\",\"datePublished\":\"2022-12-16T14:36:13+00:00\",\"dateModified\":\"2025-11-06T19:11:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/teguar.com\\\/eu\\\/de\\\/teguar-mitarbeiter-verbreiten-weihnachtsstimmung-durch-ehrenamtliche-arbeit\\\/\"},\"wordCount\":356,\"image\":{\"@id\":\"https:\\\/\\\/teguar.com\\\/eu\\\/de\\\/teguar-mitarbeiter-verbreiten-weihnachtsstimmung-durch-ehrenamtliche-arbeit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/teguar.com\\\/eu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/12\\\/HopeMatch-Volunteers-1-1024x808.jpg\",\"keywords\":[\"Teguar US HQ\"],\"articleSection\":[\"News\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/teguar.com\\\/eu\\\/de\\\/teguar-mitarbeiter-verbreiten-weihnachtsstimmung-durch-ehrenamtliche-arbeit\\\/\",\"url\":\"https:\\\/\\\/teguar.com\\\/eu\\\/de\\\/teguar-mitarbeiter-verbreiten-weihnachtsstimmung-durch-ehrenamtliche-arbeit\\\/\",\"name\":\"Teguar-Mitarbeiter verbreiten Weihnachtsstimmung durch ehrenamtliche Arbeit\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/teguar.com\\\/eu\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/teguar.com\\\/eu\\\/de\\\/teguar-mitarbeiter-verbreiten-weihnachtsstimmung-durch-ehrenamtliche-arbeit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/teguar.com\\\/eu\\\/de\\\/teguar-mitarbeiter-verbreiten-weihnachtsstimmung-durch-ehrenamtliche-arbeit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/teguar.com\\\/eu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/12\\\/HopeMatch-Volunteers-1-1024x808.jpg\",\"datePublished\":\"2022-12-16T14:36:13+00:00\",\"dateModified\":\"2025-11-06T19:11:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/teguar.com\\\/eu\\\/en\\\/#\\\/schema\\\/person\\\/919e24265800376463d11889f0a5e3d0\"},\"description\":\"Teguar kehrte im Dezember 2022 zu HOPEMatch zur\u00fcck und verpackte Weihnachtsgeschenke f\u00fcr Familien in der Gegend von Charlotte.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/teguar.com\\\/eu\\\/de\\\/teguar-mitarbeiter-verbreiten-weihnachtsstimmung-durch-ehrenamtliche-arbeit\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/teguar.com\\\/eu\\\/de\\\/teguar-mitarbeiter-verbreiten-weihnachtsstimmung-durch-ehrenamtliche-arbeit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/teguar.com\\\/eu\\\/de\\\/teguar-mitarbeiter-verbreiten-weihnachtsstimmung-durch-ehrenamtliche-arbeit\\\/#primaryimage\",\"url\":\"https:\\\/\\\/teguar.com\\\/eu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/12\\\/HopeMatch-Volunteers-1-1024x808.jpg\",\"contentUrl\":\"https:\\\/\\\/teguar.com\\\/eu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/12\\\/HopeMatch-Volunteers-1-1024x808.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/teguar.com\\\/eu\\\/de\\\/teguar-mitarbeiter-verbreiten-weihnachtsstimmung-durch-ehrenamtliche-arbeit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/teguar.com\\\/eu\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Teguar-Mitarbeiter verbreiten Weihnachtsstimmung durch ehrenamtliche Arbeit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/teguar.com\\\/eu\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/teguar.com\\\/eu\\\/en\\\/\",\"name\":\"Teguar\",\"description\":\"Industrial PCs, Medical Computers, and Rugged Tablets\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/teguar.com\\\/eu\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/teguar.com\\\/eu\\\/en\\\/#\\\/schema\\\/person\\\/919e24265800376463d11889f0a5e3d0\",\"name\":\"Emily Vrettos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/28ebae6c6002b03fe0fb5765a96a6083dcb315a2c03df7498edef7d91964a232?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/28ebae6c6002b03fe0fb5765a96a6083dcb315a2c03df7498edef7d91964a232?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/28ebae6c6002b03fe0fb5765a96a6083dcb315a2c03df7498edef7d91964a232?s=96&d=mm&r=g\",\"caption\":\"Emily Vrettos\"},\"description\":\"Emily Vrettos, Teguar's Digital Marketing Coordinator, merges her creativity with marketing skills to craft engaging content. When she isn\u2019t writing, she loves to read, cook lots of different cuisines, and travel home to her family in New England.\",\"url\":\"https:\\\/\\\/teguar.com\\\/eu\\\/de\\\/author\\\/emily-vrettos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Teguar-Mitarbeiter verbreiten Weihnachtsstimmung durch ehrenamtliche Arbeit","description":"Teguar kehrte im Dezember 2022 zu HOPEMatch zur\u00fcck und verpackte Weihnachtsgeschenke f\u00fcr Familien in der Gegend von Charlotte.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/teguar.com\/eu\/de\/teguar-mitarbeiter-verbreiten-weihnachtsstimmung-durch-ehrenamtliche-arbeit\/","og_locale":"de_DE","og_type":"article","og_title":"Teguar-Mitarbeiter verbreiten Weihnachtsstimmung durch ehrenamtliche Arbeit","og_description":"Teguar kehrte im Dezember 2022 zu HOPEMatch zur\u00fcck und verpackte Weihnachtsgeschenke f\u00fcr Familien in der Gegend von Charlotte.","og_url":"https:\/\/teguar.com\/eu\/de\/teguar-mitarbeiter-verbreiten-weihnachtsstimmung-durch-ehrenamtliche-arbeit\/","og_site_name":"Teguar","article_published_time":"2022-12-16T14:36:13+00:00","article_modified_time":"2025-11-06T19:11:11+00:00","og_image":[{"url":"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2022\/12\/HopeMatch-Volunteers-1-1024x808.jpg","type":"","width":"","height":""}],"author":"Emily Vrettos","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Emily Vrettos","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/teguar.com\/eu\/de\/teguar-mitarbeiter-verbreiten-weihnachtsstimmung-durch-ehrenamtliche-arbeit\/#article","isPartOf":{"@id":"https:\/\/teguar.com\/eu\/de\/teguar-mitarbeiter-verbreiten-weihnachtsstimmung-durch-ehrenamtliche-arbeit\/"},"author":{"name":"Emily Vrettos","@id":"https:\/\/teguar.com\/eu\/en\/#\/schema\/person\/919e24265800376463d11889f0a5e3d0"},"headline":"Teguar-Mitarbeiter verbreiten Weihnachtsstimmung durch ehrenamtliche Arbeit","datePublished":"2022-12-16T14:36:13+00:00","dateModified":"2025-11-06T19:11:11+00:00","mainEntityOfPage":{"@id":"https:\/\/teguar.com\/eu\/de\/teguar-mitarbeiter-verbreiten-weihnachtsstimmung-durch-ehrenamtliche-arbeit\/"},"wordCount":356,"image":{"@id":"https:\/\/teguar.com\/eu\/de\/teguar-mitarbeiter-verbreiten-weihnachtsstimmung-durch-ehrenamtliche-arbeit\/#primaryimage"},"thumbnailUrl":"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2022\/12\/HopeMatch-Volunteers-1-1024x808.jpg","keywords":["Teguar US HQ"],"articleSection":["News"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/teguar.com\/eu\/de\/teguar-mitarbeiter-verbreiten-weihnachtsstimmung-durch-ehrenamtliche-arbeit\/","url":"https:\/\/teguar.com\/eu\/de\/teguar-mitarbeiter-verbreiten-weihnachtsstimmung-durch-ehrenamtliche-arbeit\/","name":"Teguar-Mitarbeiter verbreiten Weihnachtsstimmung durch ehrenamtliche Arbeit","isPartOf":{"@id":"https:\/\/teguar.com\/eu\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/teguar.com\/eu\/de\/teguar-mitarbeiter-verbreiten-weihnachtsstimmung-durch-ehrenamtliche-arbeit\/#primaryimage"},"image":{"@id":"https:\/\/teguar.com\/eu\/de\/teguar-mitarbeiter-verbreiten-weihnachtsstimmung-durch-ehrenamtliche-arbeit\/#primaryimage"},"thumbnailUrl":"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2022\/12\/HopeMatch-Volunteers-1-1024x808.jpg","datePublished":"2022-12-16T14:36:13+00:00","dateModified":"2025-11-06T19:11:11+00:00","author":{"@id":"https:\/\/teguar.com\/eu\/en\/#\/schema\/person\/919e24265800376463d11889f0a5e3d0"},"description":"Teguar kehrte im Dezember 2022 zu HOPEMatch zur\u00fcck und verpackte Weihnachtsgeschenke f\u00fcr Familien in der Gegend von Charlotte.","breadcrumb":{"@id":"https:\/\/teguar.com\/eu\/de\/teguar-mitarbeiter-verbreiten-weihnachtsstimmung-durch-ehrenamtliche-arbeit\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/teguar.com\/eu\/de\/teguar-mitarbeiter-verbreiten-weihnachtsstimmung-durch-ehrenamtliche-arbeit\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/teguar.com\/eu\/de\/teguar-mitarbeiter-verbreiten-weihnachtsstimmung-durch-ehrenamtliche-arbeit\/#primaryimage","url":"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2022\/12\/HopeMatch-Volunteers-1-1024x808.jpg","contentUrl":"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2022\/12\/HopeMatch-Volunteers-1-1024x808.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/teguar.com\/eu\/de\/teguar-mitarbeiter-verbreiten-weihnachtsstimmung-durch-ehrenamtliche-arbeit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/teguar.com\/eu\/de\/"},{"@type":"ListItem","position":2,"name":"Teguar-Mitarbeiter verbreiten Weihnachtsstimmung durch ehrenamtliche Arbeit"}]},{"@type":"WebSite","@id":"https:\/\/teguar.com\/eu\/en\/#website","url":"https:\/\/teguar.com\/eu\/en\/","name":"Teguar","description":"Industrial PCs, Medical Computers, and Rugged Tablets","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/teguar.com\/eu\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/teguar.com\/eu\/en\/#\/schema\/person\/919e24265800376463d11889f0a5e3d0","name":"Emily Vrettos","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/28ebae6c6002b03fe0fb5765a96a6083dcb315a2c03df7498edef7d91964a232?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/28ebae6c6002b03fe0fb5765a96a6083dcb315a2c03df7498edef7d91964a232?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/28ebae6c6002b03fe0fb5765a96a6083dcb315a2c03df7498edef7d91964a232?s=96&d=mm&r=g","caption":"Emily Vrettos"},"description":"Emily Vrettos, Teguar's Digital Marketing Coordinator, merges her creativity with marketing skills to craft engaging content. When she isn\u2019t writing, she loves to read, cook lots of different cuisines, and travel home to her family in New England.","url":"https:\/\/teguar.com\/eu\/de\/author\/emily-vrettos\/"}]}},"_links":{"self":[{"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/posts\/2244650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/comments?post=2244650"}],"version-history":[{"count":1,"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/posts\/2244650\/revisions"}],"predecessor-version":[{"id":2244652,"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/posts\/2244650\/revisions\/2244652"}],"wp:attachment":[{"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/media?parent=2244650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/categories?post=2244650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/tags?post=2244650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}