{"id":2244337,"date":"2016-12-09T10:00:00","date_gmt":"2016-12-09T10:00:00","guid":{"rendered":"https:\/\/teguar.com\/eu\/eine-aktualisierte-generation-von-medizinischen-all-in-one-computern\/"},"modified":"2025-11-06T19:12:55","modified_gmt":"2025-11-06T19:12:55","slug":"eine-aktualisierte-generation-von-medizinischen-all-in-one-computern","status":"publish","type":"post","link":"https:\/\/teguar.com\/eu\/de\/eine-aktualisierte-generation-von-medizinischen-all-in-one-computern\/","title":{"rendered":"Eine aktualisierte Generation von medizinischen All-in-One-Computern"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Charlotte, NC<\/strong> &#8211; Teguar stellt seinen neuesten l\u00fcfterlosen Panel-PC f\u00fcr den medizinischen Bereich vor, die TM-3110 Serie. Der 19&#8243; TM-3110-19 und der 21,5&#8243; TM-3110-22 sind beide mit dem 5. Generation Intel Broadwell-basierten i5-5200U 2.20G \/i7-5500U 2.40G ausgestattet. Die Grafikfunktionen und die Gesamtleistung wurden gegen\u00fcber der Vorg\u00e4ngergeneration TM-3010 deutlich verbessert. Dar\u00fcber hinaus verf\u00fcgt die Serie \u00fcber neue USB 3.0-Anschl\u00fcsse und Videoausgangs-Anzeigen. Benutzer k\u00f6nnen zwei externe Monitore anschlie\u00dfen, um bis zu drei verschiedene Bilder gleichzeitig anzuzeigen.    <\/p>\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" alt=\"Teguar TM-3110-19 medizinischer Touchscreen-Computer\" src=\"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/TM-3110-19_Small-1.jpg\" style=\"float:right;padding:10px\"\/>Die Broadwell CPU verbraucht weniger Strom als die CPUs der 4. Generation und bietet eine bessere Leistung und eine l\u00e4ngere Akkulaufzeit. Der Prozessor unterst\u00fctzt neue Funktionen wie 4K-Video, drahtloses Display und integrierte TPM-Sicherheit mit schneller Datenverschl\u00fcsselung. <\/p>\n\n<p class=\"wp-block-paragraph\">Mit Hilfe eines optionalen externen Moduls kann die neue Serie mit vier PCI-E-Erweiterungssteckpl\u00e4tzen ausgestattet werden, die insbesondere f\u00fcr Anwendungen im medizinischen Bereich, wie z.B. medizinische Bildaufnahmekarten, n\u00fctzlich sind. Die Hochgeschwindigkeits-Eingangs- und Ausgangsports erf\u00fcllen die Anforderungen verschiedener medizinischer Ger\u00e4te und Entwicklungsplattformen. <\/p>\n\n<p class=\"wp-block-paragraph\">Die TP-3110 Serie ist aus antibakteriellem Kunststoff gefertigt, der das Wachstum von MRSA und anderen Bakterien auf den Ger\u00e4ten verhindert. Die antibakterielle Formel ist mit dem PC+ABS-Kunststoff des Geh\u00e4uses vermischt, so dass selbst bei regelm\u00e4\u00dfiger Sterilisation mit Alkohol und anderen Desinfektionsmitteln die antibakteriellen Eigenschaften des Ger\u00e4ts nicht beeintr\u00e4chtigt werden. <\/p>\n\n<p class=\"wp-block-paragraph\">Die neuen medizinischen Panel-PCs verf\u00fcgen \u00fcber einen projiziert-kapazitiven Touchscreen (10 Punkte), Wischbewegungen mit einem Finger und Zoomfunktionen. Da im medizinischen Bereich h\u00e4ufig Handschuhe erforderlich sind, wurde der Touchscreen so aktualisiert, dass er von Benutzern mit bis zu vier Paar Latexhandschuhen bedient werden kann. Der Frontrahmen ist nach IP65 wasserdicht, so dass er gereinigt werden kann, ohne die internen Komponenten zu besch\u00e4digen. Der TP-3110 verf\u00fcgt au\u00dferdem \u00fcber eine &#8222;Clean Me&#8220;-Funktion, die den Bildschirm sperrt, so dass das Ger\u00e4t w\u00e4hrend der Reinigung nicht ausgeschaltet werden muss.   <\/p>\n\n<p class=\"wp-block-paragraph\">Die Modelle TP-3110-19\/22 verf\u00fcgen \u00fcber eine optionale Isolierung der LAN-, COM- und USB-Anschl\u00fcsse, um sicherzustellen, dass alle medizinischen Ger\u00e4te in der Umgebung des Patienten korrekt und sicher ohne St\u00f6rungen funktionieren. Die Serie ist nach UL 60601-1 3rd Edition medizinisch zertifiziert, um die Sicherheit der Patienten zu gew\u00e4hrleisten. Au\u00dferdem ist eine optionale Batterie-Backup-L\u00f6sung erh\u00e4ltlich, die das Ger\u00e4t im Falle eines Stromausfalls bis zu 20 Minuten lang mit Strom versorgt.  <\/p>\n\n<p class=\"wp-block-paragraph\">Wenn Sie weitere Informationen w\u00fcnschen oder spezielle Anforderungen haben, wenden Sie sich bitte an das Teguar-Verkaufsteam unter <a href=\"&#x6d;a&#x69;&#x6c;t&#x6f;&#x3a;s&#x61;&#x6c;e&#x73;&#x40;t&#x65;&#x67;u&#x61;&#114;.&#x63;&#111;m\">&#x73;a&#x6c;e&#x73;&#64;t&#x65;g&#x75;a&#x72;&#46;c&#x6f;m.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Charlotte, NC &#8211; Teguar stellt seinen neuesten l\u00fcfterlosen Panel-PC f\u00fcr den medizinischen Bereich vor, die TM-3110 Serie. Der 19&#8243; TM-3110-19 und der 21,5&#8243; TM-3110-22 sind beide mit dem 5. Generation Intel Broadwell-basierten i5-5200U 2.20G \/i7-5500U 2.40G ausgestattet. Die Grafikfunktionen und die Gesamtleistung wurden gegen\u00fcber der Vorg\u00e4ngergeneration TM-3010 deutlich verbessert. Dar\u00fcber hinaus verf\u00fcgt die Serie \u00fcber [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":2244339,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2300],"tags":[2305,2297,2307,2340,2327],"class_list":["post-2244337","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-product-announcements","tag-iec-60601-1-2","tag-medical-computer","tag-medical-touchscreen","tag-touchscreen-cleaning","tag-tpm-computer"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Eine aktualisierte Generation von Teguar Medical All-In-One Computern<\/title>\n<meta name=\"description\" content=\"Teguar Computers bietet industrielle und medizinische Computer f\u00fcr den Schaltschrankeinbau, All-in-One-Computer, Touchscreen-Computer, Box-Computer und wasserdichte Computer.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/teguar.com\/eu\/de\/eine-aktualisierte-generation-von-medizinischen-all-in-one-computern\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eine aktualisierte Generation von medizinischen All-in-One-Computern\" \/>\n<meta property=\"og:description\" content=\"Teguar Computers bietet industrielle und medizinische Computer f\u00fcr den Schaltschrankeinbau, All-in-One-Computer, Touchscreen-Computer, Box-Computer und wasserdichte Computer.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/teguar.com\/eu\/de\/eine-aktualisierte-generation-von-medizinischen-all-in-one-computern\/\" \/>\n<meta property=\"og:site_name\" content=\"Teguar\" \/>\n<meta property=\"article:published_time\" content=\"2016-12-09T10:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-06T19:12:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/TM-3110-19_Small-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Teguar Computers\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Teguar Computers\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/teguar.com\\\/eu\\\/de\\\/eine-aktualisierte-generation-von-medizinischen-all-in-one-computern\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/teguar.com\\\/eu\\\/de\\\/eine-aktualisierte-generation-von-medizinischen-all-in-one-computern\\\/\"},\"author\":{\"name\":\"Teguar Computers\",\"@id\":\"https:\\\/\\\/teguar.com\\\/eu\\\/en\\\/#\\\/schema\\\/person\\\/8656a31ca77439553397cd30c0b308f6\"},\"headline\":\"Eine aktualisierte Generation von medizinischen All-in-One-Computern\",\"datePublished\":\"2016-12-09T10:00:00+00:00\",\"dateModified\":\"2025-11-06T19:12:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/teguar.com\\\/eu\\\/de\\\/eine-aktualisierte-generation-von-medizinischen-all-in-one-computern\\\/\"},\"wordCount\":420,\"image\":{\"@id\":\"https:\\\/\\\/teguar.com\\\/eu\\\/de\\\/eine-aktualisierte-generation-von-medizinischen-all-in-one-computern\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/teguar.com\\\/eu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/08\\\/TM-3110-19_Small-1-1.jpg\",\"keywords\":[\"IEC 60601-1-2\",\"medical computer\",\"Medical Touchscreen\",\"touchscreen cleaning\",\"TPM Computer\"],\"articleSection\":[\"Product Announcements\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/teguar.com\\\/eu\\\/de\\\/eine-aktualisierte-generation-von-medizinischen-all-in-one-computern\\\/\",\"url\":\"https:\\\/\\\/teguar.com\\\/eu\\\/de\\\/eine-aktualisierte-generation-von-medizinischen-all-in-one-computern\\\/\",\"name\":\"Eine aktualisierte Generation von Teguar Medical All-In-One Computern\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/teguar.com\\\/eu\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/teguar.com\\\/eu\\\/de\\\/eine-aktualisierte-generation-von-medizinischen-all-in-one-computern\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/teguar.com\\\/eu\\\/de\\\/eine-aktualisierte-generation-von-medizinischen-all-in-one-computern\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/teguar.com\\\/eu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/08\\\/TM-3110-19_Small-1-1.jpg\",\"datePublished\":\"2016-12-09T10:00:00+00:00\",\"dateModified\":\"2025-11-06T19:12:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/teguar.com\\\/eu\\\/en\\\/#\\\/schema\\\/person\\\/8656a31ca77439553397cd30c0b308f6\"},\"description\":\"Teguar Computers bietet industrielle und medizinische Computer f\u00fcr den Schaltschrankeinbau, All-in-One-Computer, Touchscreen-Computer, Box-Computer und wasserdichte Computer.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/teguar.com\\\/eu\\\/de\\\/eine-aktualisierte-generation-von-medizinischen-all-in-one-computern\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/teguar.com\\\/eu\\\/de\\\/eine-aktualisierte-generation-von-medizinischen-all-in-one-computern\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/teguar.com\\\/eu\\\/de\\\/eine-aktualisierte-generation-von-medizinischen-all-in-one-computern\\\/#primaryimage\",\"url\":\"https:\\\/\\\/teguar.com\\\/eu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/08\\\/TM-3110-19_Small-1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/teguar.com\\\/eu\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/08\\\/TM-3110-19_Small-1-1.jpg\",\"width\":300,\"height\":300,\"caption\":\"Teguar TM-3110-19 medical touchscreen computer\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/teguar.com\\\/eu\\\/de\\\/eine-aktualisierte-generation-von-medizinischen-all-in-one-computern\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/teguar.com\\\/eu\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eine aktualisierte Generation von medizinischen All-in-One-Computern\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/teguar.com\\\/eu\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/teguar.com\\\/eu\\\/en\\\/\",\"name\":\"Teguar\",\"description\":\"Industrial PCs, Medical Computers, and Rugged Tablets\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/teguar.com\\\/eu\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/teguar.com\\\/eu\\\/en\\\/#\\\/schema\\\/person\\\/8656a31ca77439553397cd30c0b308f6\",\"name\":\"Teguar Computers\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5fdee48d23c69713cc8714619cf115c768223bda2d66e69d27baa6a0aacb67e7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5fdee48d23c69713cc8714619cf115c768223bda2d66e69d27baa6a0aacb67e7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5fdee48d23c69713cc8714619cf115c768223bda2d66e69d27baa6a0aacb67e7?s=96&d=mm&r=g\",\"caption\":\"Teguar Computers\"},\"url\":\"https:\\\/\\\/teguar.com\\\/eu\\\/de\\\/author\\\/teguarcomputers\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Eine aktualisierte Generation von Teguar Medical All-In-One Computern","description":"Teguar Computers bietet industrielle und medizinische Computer f\u00fcr den Schaltschrankeinbau, All-in-One-Computer, Touchscreen-Computer, Box-Computer und wasserdichte Computer.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/teguar.com\/eu\/de\/eine-aktualisierte-generation-von-medizinischen-all-in-one-computern\/","og_locale":"de_DE","og_type":"article","og_title":"Eine aktualisierte Generation von medizinischen All-in-One-Computern","og_description":"Teguar Computers bietet industrielle und medizinische Computer f\u00fcr den Schaltschrankeinbau, All-in-One-Computer, Touchscreen-Computer, Box-Computer und wasserdichte Computer.","og_url":"https:\/\/teguar.com\/eu\/de\/eine-aktualisierte-generation-von-medizinischen-all-in-one-computern\/","og_site_name":"Teguar","article_published_time":"2016-12-09T10:00:00+00:00","article_modified_time":"2025-11-06T19:12:55+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/TM-3110-19_Small-1-1.jpg","type":"image\/jpeg"}],"author":"Teguar Computers","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Teguar Computers","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/teguar.com\/eu\/de\/eine-aktualisierte-generation-von-medizinischen-all-in-one-computern\/#article","isPartOf":{"@id":"https:\/\/teguar.com\/eu\/de\/eine-aktualisierte-generation-von-medizinischen-all-in-one-computern\/"},"author":{"name":"Teguar Computers","@id":"https:\/\/teguar.com\/eu\/en\/#\/schema\/person\/8656a31ca77439553397cd30c0b308f6"},"headline":"Eine aktualisierte Generation von medizinischen All-in-One-Computern","datePublished":"2016-12-09T10:00:00+00:00","dateModified":"2025-11-06T19:12:55+00:00","mainEntityOfPage":{"@id":"https:\/\/teguar.com\/eu\/de\/eine-aktualisierte-generation-von-medizinischen-all-in-one-computern\/"},"wordCount":420,"image":{"@id":"https:\/\/teguar.com\/eu\/de\/eine-aktualisierte-generation-von-medizinischen-all-in-one-computern\/#primaryimage"},"thumbnailUrl":"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/TM-3110-19_Small-1-1.jpg","keywords":["IEC 60601-1-2","medical computer","Medical Touchscreen","touchscreen cleaning","TPM Computer"],"articleSection":["Product Announcements"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/teguar.com\/eu\/de\/eine-aktualisierte-generation-von-medizinischen-all-in-one-computern\/","url":"https:\/\/teguar.com\/eu\/de\/eine-aktualisierte-generation-von-medizinischen-all-in-one-computern\/","name":"Eine aktualisierte Generation von Teguar Medical All-In-One Computern","isPartOf":{"@id":"https:\/\/teguar.com\/eu\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/teguar.com\/eu\/de\/eine-aktualisierte-generation-von-medizinischen-all-in-one-computern\/#primaryimage"},"image":{"@id":"https:\/\/teguar.com\/eu\/de\/eine-aktualisierte-generation-von-medizinischen-all-in-one-computern\/#primaryimage"},"thumbnailUrl":"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/TM-3110-19_Small-1-1.jpg","datePublished":"2016-12-09T10:00:00+00:00","dateModified":"2025-11-06T19:12:55+00:00","author":{"@id":"https:\/\/teguar.com\/eu\/en\/#\/schema\/person\/8656a31ca77439553397cd30c0b308f6"},"description":"Teguar Computers bietet industrielle und medizinische Computer f\u00fcr den Schaltschrankeinbau, All-in-One-Computer, Touchscreen-Computer, Box-Computer und wasserdichte Computer.","breadcrumb":{"@id":"https:\/\/teguar.com\/eu\/de\/eine-aktualisierte-generation-von-medizinischen-all-in-one-computern\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/teguar.com\/eu\/de\/eine-aktualisierte-generation-von-medizinischen-all-in-one-computern\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/teguar.com\/eu\/de\/eine-aktualisierte-generation-von-medizinischen-all-in-one-computern\/#primaryimage","url":"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/TM-3110-19_Small-1-1.jpg","contentUrl":"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/TM-3110-19_Small-1-1.jpg","width":300,"height":300,"caption":"Teguar TM-3110-19 medical touchscreen computer"},{"@type":"BreadcrumbList","@id":"https:\/\/teguar.com\/eu\/de\/eine-aktualisierte-generation-von-medizinischen-all-in-one-computern\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/teguar.com\/eu\/de\/"},{"@type":"ListItem","position":2,"name":"Eine aktualisierte Generation von medizinischen All-in-One-Computern"}]},{"@type":"WebSite","@id":"https:\/\/teguar.com\/eu\/en\/#website","url":"https:\/\/teguar.com\/eu\/en\/","name":"Teguar","description":"Industrial PCs, Medical Computers, and Rugged Tablets","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/teguar.com\/eu\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/teguar.com\/eu\/en\/#\/schema\/person\/8656a31ca77439553397cd30c0b308f6","name":"Teguar Computers","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/5fdee48d23c69713cc8714619cf115c768223bda2d66e69d27baa6a0aacb67e7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5fdee48d23c69713cc8714619cf115c768223bda2d66e69d27baa6a0aacb67e7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5fdee48d23c69713cc8714619cf115c768223bda2d66e69d27baa6a0aacb67e7?s=96&d=mm&r=g","caption":"Teguar Computers"},"url":"https:\/\/teguar.com\/eu\/de\/author\/teguarcomputers\/"}]}},"_links":{"self":[{"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/posts\/2244337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/comments?post=2244337"}],"version-history":[{"count":1,"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/posts\/2244337\/revisions"}],"predecessor-version":[{"id":2244341,"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/posts\/2244337\/revisions\/2244341"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/media\/2244339"}],"wp:attachment":[{"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/media?parent=2244337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/categories?post=2244337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/tags?post=2244337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}