{"id":2244273,"date":"2015-10-28T10:00:00","date_gmt":"2015-10-28T10:00:00","guid":{"rendered":"https:\/\/teguar.com\/eu\/medizinischer-computer-stellt-benutzerfreundlichkeit-in-den-vordergrund\/"},"modified":"2025-11-06T19:13:05","modified_gmt":"2025-11-06T19:13:05","slug":"medizinischer-computer-stellt-benutzerfreundlichkeit-in-den-vordergrund","status":"publish","type":"post","link":"https:\/\/teguar.com\/eu\/de\/medizinischer-computer-stellt-benutzerfreundlichkeit-in-den-vordergrund\/","title":{"rendered":"Medizinischer Computer stellt Benutzerfreundlichkeit in den Vordergrund"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/TM-4010-15PNews_Image_6.jpg\" alt=\"Produkt-Spotlight Neuer UX First Medical Computer\" class=\"wp-image-10210\"\/><figcaption class=\"wp-element-caption\"><strong>Teguar stellt den TM-4010-15P mit benutzerfreundlichen Funktionen (UX) vor<\/strong><\/figcaption><\/figure>\n\n<p><strong>Charlotte, NC<\/strong> &#8211; Teguar Computers, ein f\u00fchrender Hersteller von medizinischen Computern, bringt einen neuen medizinischen Computer auf den Markt, der speziell f\u00fcr Patienten und medizinisches Fachpersonal entwickelt wurde. Das Design des TM-4010-15P geht \u00fcber die Anforderungen an Betriebssystem und Software in der Hardware hinaus. Der medizinische Computer verf\u00fcgt \u00fcber mehrere Funktionen, die speziell zur Verbesserung der Benutzerfreundlichkeit entwickelt wurden.  <\/p>\n\n<p>Jacob Valdez, Account Manager bei Teguar Computers, kommentierte die Produktver\u00f6ffentlichung in diesem Herbst. Er sagte <strong>  &#8222;<em>Ich bin begeistert, dass ich meinen Kunden ein so einzigartiges Produkt anbieten kann. Der TP-4010-15P wurde so konzipiert, dass das Benutzererlebnis wirklich an erster Stelle steht. Die Technik ist f\u00fcr Menschen da, nicht nur f\u00fcr Programme.  <\/em>&#8222;<\/strong><\/p>\n\n<p>Der TM-4010-15P ist f\u00fcr drei Hauptnutzer gedacht: Patienten, medizinisches Fachpersonal und HIT (Health Information Technology).<\/p>\n\n<p><img decoding=\"async\" alt=\"Teguar TM-4010-15P Medizinischer Computer mit Touchscreen\" src=\"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/250x250tm-4010-15P_title_w_gloves_.jpg\" style=\"float:right;padding:10px\"\/>Die Interaktion des Patienten mit dem neuen medizinischen Computer von Teguar wird durch die Funktionen f\u00fcr Sicherheit, Privatsph\u00e4re und Wellness-Umgebung verbessert. Die 4KV-Isolationsoption bietet Patientenschutz. Wenn der TM-4010-15P Medizincomputer an medizinische Ger\u00e4te angeschlossen ist, die direkt am Patienten verwendet werden, sch\u00fctzt die 4KV-Isolierung vor Spannungsspitzen, die lebenswichtige medizinische Ger\u00e4te st\u00f6ren k\u00f6nnten. Diese Funktion gew\u00e4hrleistet au\u00dferdem eine klare Signal\u00fcbertragung der \u00fcberwachten Informationen. Wie die meisten medizinischen Computer ist auch der TM-4010-15P nach EN\/UL 60601 zertifiziert, was ebenfalls sicherstellt, dass kein elektrischer Schlag auf den Patienten \u00fcbertragen wird.    <\/p>\n\n<p>Der TM-4010-15P bietet einige Funktionen zum Schutz der Privatsph\u00e4re des Patienten. Ein Hotkey auf der Vorderseite des Computers deaktiviert die Webcam, und eine Stummschalttaste schaltet auch die Lautsprecher\/Mikrofone aus. W\u00e4hrend es f\u00fcr IT-Profis ein Leichtes ist, Webcams und Mikrofone \u00fcber die Bildschirmeinstellungen zu deaktivieren, ist das Hotkey-Design des TM-4010-15P dazu gedacht, Patienten und \u00c4rzten Sicherheit zu bieten. Die Gewissheit, dass Kameras und Mikrofone nicht aktiviert sind, wenn sie nicht erw\u00fcnscht sind, verringert die Unruhe. Die Datensicherheit ist ein weiterer wichtiger Aspekt, um die Privatsph\u00e4re des Patienten zu sch\u00fctzen. Das in die Hardware eingebaute TPM sch\u00fctzt die Privatsph\u00e4re, indem es die Daten vor Diebstahl oder Manipulation durch Hacker von au\u00dfen sch\u00fctzt.       <\/p>\n\n<p>Die Wellness-Funktionen f\u00fcr Patienten sind in das Geh\u00e4use des Computers integriert. Das l\u00fcfterlose Design und die abgerundeten Ecken sorgen im wahrsten Sinne des Wortes f\u00fcr eine ger\u00e4uschfreie \u00c4sthetik. Au\u00dferdem l\u00e4sst sich das abgerundete Design mit der vollst\u00e4ndig flachen Vorderseite leicht und schnell reinigen und bietet nur wenige Spalten, in denen sich Staub und Schmutz ansammeln k\u00f6nnen. Wie viele medizinische Computer von Teguar ist auch der TM-3010-15P mit einer antibakteriellen Beschichtung versehen, die die Ausbreitung von Krankheiten verhindert.   <\/p>\n\n<p><strong><em>Diese Details machen den Unterschied in einer heilenden Umgebung aus. Funktionen sind wichtig f\u00fcr ein hervorragendes Benutzererlebnis. Die Entwickler des TM-4010-15P haben daran gearbeitet, eine benutzerorientierte medizinische Computerplattform zu schaffen.    <\/em><\/strong><\/p>\n\n<p>F\u00fcr medizinisches Fachpersonal bieten die speziellen Bildschirmfunktionen eine nahtlose Benutzererfahrung. Der projektiv-kapazitive (P-Cap) Touchscreen des TM-4010-15P wurde speziell f\u00fcr den Einsatz im Krankenhaus entwickelt. Alle P-Cap-Bildschirme werden mit einem geringen menschlichen Stromverbrauch betrieben und m\u00fcssen normalerweise mit der Haut direkt auf dem Bildschirm verwendet werden. Der P-Cap-Bildschirm des TM-4010-15P ist besonders empfindlich, so dass er mit bis zu vier Schichten medizinischer Handschuhe verwendet werden kann. Dies erm\u00f6glicht eine einfache Verwendung in Umgebungen, in denen aseptische Techniken erforderlich sind. Der Bildschirm ist au\u00dferdem so konzipiert, dass er mit zehn Ber\u00fchrungspunkten arbeitet. Dies erm\u00f6glicht eine vollst\u00e4ndige physische Interaktion mit der Software, die f\u00fcr die Interaktion mit der menschlichen Hand programmiert ist, und die Verwendung der Zoomfunktion f\u00fcr eine bessere Sehsch\u00e4rfe auf medizinischen Bildschirmen.      <\/p>\n\n<p>Fachleute f\u00fcr Gesundheitsinformatik bleiben nicht au\u00dfen vor, wenn es darum geht, den Anwender in den Mittelpunkt zu stellen. Der medizinische Computer TM-4010-15P verf\u00fcgt \u00fcber Funktionen, die vielseitig sind und sich an neue Technologien anpassen k\u00f6nnen. Er verf\u00fcgt \u00fcber einen optionalen Erweiterungssteckplatz, so dass der Computer an die sich \u00e4ndernden Anforderungen von Programmen und Anwendungen angepasst werden kann. Au\u00dferdem ist eine programmierbare Funktionstaste enthalten, die von einem Spezialisten f\u00fcr Informationstechnologie an die jeweilige Anwendung angepasst werden kann.   <\/p>\n\n<p>Insgesamt bietet der TM-4010-15P mit der Intel Celeron J1900 Quad Core 2.0GHz CPU und bis zu 8GB RAM eine sehr zuverl\u00e4ssige Plattform. Wie bei allen Teguar-Computern sind kundenspezifische Optionen verf\u00fcgbar, um die ideale Endanwendung und Serverkommunikationsumgebung zu finden. F\u00fcr weitere Informationen \u00fcber den TM-4010-15P Medical Grade Computer wenden Sie sich bitte an das Teguar Vertriebsteam unter <a href=\"&#109;a&#x69;l&#x74;o&#x3a;S&#x61;l&#x65;s&#x40;&#116;&#x65;&#103;u&#97;r&#x2e;c&#x6f;m\" target=\"_blank\" rel=\"noreferrer noopener\">&#x53;&#x61;&#108;es&#64;&#x74;&#x65;&#x67;&#117;ar&#x2e;&#x63;&#x6f;&#109;.<\/a>  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Charlotte, NC &#8211; Teguar Computers, ein f\u00fchrender Hersteller von medizinischen Computern, bringt einen neuen medizinischen Computer auf den Markt, der speziell f\u00fcr Patienten und medizinisches Fachpersonal entwickelt wurde. Das Design des TM-4010-15P geht \u00fcber die Anforderungen an Betriebssystem und Software in der Hardware hinaus. Der medizinische Computer verf\u00fcgt \u00fcber mehrere Funktionen, die speziell zur Verbesserung [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":2244275,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2809],"tags":[2881,2903,2863,2956],"class_list":["post-2244273","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-produktankundigungen","tag-iec-60601-1-2","tag-lufterlose-computer","tag-medizinischer-computer","tag-tpm-computer"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.8 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Medizinischer Computer stellt Benutzerfreundlichkeit in den Vordergrund | Teguar<\/title>\n<meta name=\"description\" content=\"Es wurde ein neuer medizinischer Computer eingef\u00fchrt, der speziell f\u00fcr die Benutzererfahrung entwickelt wurde.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/teguar.com\/eu\/de\/medizinischer-computer-stellt-benutzerfreundlichkeit-in-den-vordergrund\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Medizinischer Computer stellt Benutzerfreundlichkeit in den Vordergrund\" \/>\n<meta property=\"og:description\" content=\"Es wurde ein neuer medizinischer Computer eingef\u00fchrt, der speziell f\u00fcr die Benutzererfahrung entwickelt wurde.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/teguar.com\/eu\/de\/medizinischer-computer-stellt-benutzerfreundlichkeit-in-den-vordergrund\/\" \/>\n<meta property=\"og:site_name\" content=\"Teguar\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-28T10:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-06T19:13:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/TM-4010-15PNews_Image_6-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Teguar Computers\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Teguar Computers\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/teguar.com\/eu\/de\/medizinischer-computer-stellt-benutzerfreundlichkeit-in-den-vordergrund\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/teguar.com\/eu\/de\/medizinischer-computer-stellt-benutzerfreundlichkeit-in-den-vordergrund\/\"},\"author\":{\"name\":\"Teguar Computers\",\"@id\":\"https:\/\/teguar.com\/eu\/en\/#\/schema\/person\/8656a31ca77439553397cd30c0b308f6\"},\"headline\":\"Medizinischer Computer stellt Benutzerfreundlichkeit in den Vordergrund\",\"datePublished\":\"2015-10-28T10:00:00+00:00\",\"dateModified\":\"2025-11-06T19:13:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/teguar.com\/eu\/de\/medizinischer-computer-stellt-benutzerfreundlichkeit-in-den-vordergrund\/\"},\"wordCount\":789,\"image\":{\"@id\":\"https:\/\/teguar.com\/eu\/de\/medizinischer-computer-stellt-benutzerfreundlichkeit-in-den-vordergrund\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/TM-4010-15PNews_Image_6-1.jpg\",\"keywords\":[\"IEC 60601-1-2\",\"L\u00fcfterlose Computer\",\"medizinischer Computer\",\"TPM-Computer\"],\"articleSection\":[\"Produkt-Ank\u00fcndigungen\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/teguar.com\/eu\/de\/medizinischer-computer-stellt-benutzerfreundlichkeit-in-den-vordergrund\/\",\"url\":\"https:\/\/teguar.com\/eu\/de\/medizinischer-computer-stellt-benutzerfreundlichkeit-in-den-vordergrund\/\",\"name\":\"Medizinischer Computer stellt Benutzerfreundlichkeit in den Vordergrund | Teguar\",\"isPartOf\":{\"@id\":\"https:\/\/teguar.com\/eu\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/teguar.com\/eu\/de\/medizinischer-computer-stellt-benutzerfreundlichkeit-in-den-vordergrund\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/teguar.com\/eu\/de\/medizinischer-computer-stellt-benutzerfreundlichkeit-in-den-vordergrund\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/TM-4010-15PNews_Image_6-1.jpg\",\"datePublished\":\"2015-10-28T10:00:00+00:00\",\"dateModified\":\"2025-11-06T19:13:05+00:00\",\"author\":{\"@id\":\"https:\/\/teguar.com\/eu\/en\/#\/schema\/person\/8656a31ca77439553397cd30c0b308f6\"},\"description\":\"Es wurde ein neuer medizinischer Computer eingef\u00fchrt, der speziell f\u00fcr die Benutzererfahrung entwickelt wurde.\",\"breadcrumb\":{\"@id\":\"https:\/\/teguar.com\/eu\/de\/medizinischer-computer-stellt-benutzerfreundlichkeit-in-den-vordergrund\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/teguar.com\/eu\/de\/medizinischer-computer-stellt-benutzerfreundlichkeit-in-den-vordergrund\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/teguar.com\/eu\/de\/medizinischer-computer-stellt-benutzerfreundlichkeit-in-den-vordergrund\/#primaryimage\",\"url\":\"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/TM-4010-15PNews_Image_6-1.jpg\",\"contentUrl\":\"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/TM-4010-15PNews_Image_6-1.jpg\",\"width\":600,\"height\":300,\"caption\":\"Product Spotlight New UX First Medical Computer\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/teguar.com\/eu\/de\/medizinischer-computer-stellt-benutzerfreundlichkeit-in-den-vordergrund\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/teguar.com\/eu\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Medizinischer Computer stellt Benutzerfreundlichkeit in den Vordergrund\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/teguar.com\/eu\/en\/#website\",\"url\":\"https:\/\/teguar.com\/eu\/en\/\",\"name\":\"Teguar\",\"description\":\"Industrial PCs, Medical Computers, and Rugged Tablets\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/teguar.com\/eu\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/teguar.com\/eu\/en\/#\/schema\/person\/8656a31ca77439553397cd30c0b308f6\",\"name\":\"Teguar Computers\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/5fdee48d23c69713cc8714619cf115c768223bda2d66e69d27baa6a0aacb67e7?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5fdee48d23c69713cc8714619cf115c768223bda2d66e69d27baa6a0aacb67e7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5fdee48d23c69713cc8714619cf115c768223bda2d66e69d27baa6a0aacb67e7?s=96&d=mm&r=g\",\"caption\":\"Teguar Computers\"},\"url\":\"https:\/\/teguar.com\/eu\/de\/author\/teguarcomputers\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Medizinischer Computer stellt Benutzerfreundlichkeit in den Vordergrund | Teguar","description":"Es wurde ein neuer medizinischer Computer eingef\u00fchrt, der speziell f\u00fcr die Benutzererfahrung entwickelt wurde.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/teguar.com\/eu\/de\/medizinischer-computer-stellt-benutzerfreundlichkeit-in-den-vordergrund\/","og_locale":"de_DE","og_type":"article","og_title":"Medizinischer Computer stellt Benutzerfreundlichkeit in den Vordergrund","og_description":"Es wurde ein neuer medizinischer Computer eingef\u00fchrt, der speziell f\u00fcr die Benutzererfahrung entwickelt wurde.","og_url":"https:\/\/teguar.com\/eu\/de\/medizinischer-computer-stellt-benutzerfreundlichkeit-in-den-vordergrund\/","og_site_name":"Teguar","article_published_time":"2015-10-28T10:00:00+00:00","article_modified_time":"2025-11-06T19:13:05+00:00","og_image":[{"width":600,"height":300,"url":"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/TM-4010-15PNews_Image_6-1.jpg","type":"image\/jpeg"}],"author":"Teguar Computers","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Teguar Computers","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/teguar.com\/eu\/de\/medizinischer-computer-stellt-benutzerfreundlichkeit-in-den-vordergrund\/#article","isPartOf":{"@id":"https:\/\/teguar.com\/eu\/de\/medizinischer-computer-stellt-benutzerfreundlichkeit-in-den-vordergrund\/"},"author":{"name":"Teguar Computers","@id":"https:\/\/teguar.com\/eu\/en\/#\/schema\/person\/8656a31ca77439553397cd30c0b308f6"},"headline":"Medizinischer Computer stellt Benutzerfreundlichkeit in den Vordergrund","datePublished":"2015-10-28T10:00:00+00:00","dateModified":"2025-11-06T19:13:05+00:00","mainEntityOfPage":{"@id":"https:\/\/teguar.com\/eu\/de\/medizinischer-computer-stellt-benutzerfreundlichkeit-in-den-vordergrund\/"},"wordCount":789,"image":{"@id":"https:\/\/teguar.com\/eu\/de\/medizinischer-computer-stellt-benutzerfreundlichkeit-in-den-vordergrund\/#primaryimage"},"thumbnailUrl":"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/TM-4010-15PNews_Image_6-1.jpg","keywords":["IEC 60601-1-2","L\u00fcfterlose Computer","medizinischer Computer","TPM-Computer"],"articleSection":["Produkt-Ank\u00fcndigungen"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/teguar.com\/eu\/de\/medizinischer-computer-stellt-benutzerfreundlichkeit-in-den-vordergrund\/","url":"https:\/\/teguar.com\/eu\/de\/medizinischer-computer-stellt-benutzerfreundlichkeit-in-den-vordergrund\/","name":"Medizinischer Computer stellt Benutzerfreundlichkeit in den Vordergrund | Teguar","isPartOf":{"@id":"https:\/\/teguar.com\/eu\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/teguar.com\/eu\/de\/medizinischer-computer-stellt-benutzerfreundlichkeit-in-den-vordergrund\/#primaryimage"},"image":{"@id":"https:\/\/teguar.com\/eu\/de\/medizinischer-computer-stellt-benutzerfreundlichkeit-in-den-vordergrund\/#primaryimage"},"thumbnailUrl":"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/TM-4010-15PNews_Image_6-1.jpg","datePublished":"2015-10-28T10:00:00+00:00","dateModified":"2025-11-06T19:13:05+00:00","author":{"@id":"https:\/\/teguar.com\/eu\/en\/#\/schema\/person\/8656a31ca77439553397cd30c0b308f6"},"description":"Es wurde ein neuer medizinischer Computer eingef\u00fchrt, der speziell f\u00fcr die Benutzererfahrung entwickelt wurde.","breadcrumb":{"@id":"https:\/\/teguar.com\/eu\/de\/medizinischer-computer-stellt-benutzerfreundlichkeit-in-den-vordergrund\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/teguar.com\/eu\/de\/medizinischer-computer-stellt-benutzerfreundlichkeit-in-den-vordergrund\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/teguar.com\/eu\/de\/medizinischer-computer-stellt-benutzerfreundlichkeit-in-den-vordergrund\/#primaryimage","url":"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/TM-4010-15PNews_Image_6-1.jpg","contentUrl":"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/TM-4010-15PNews_Image_6-1.jpg","width":600,"height":300,"caption":"Product Spotlight New UX First Medical Computer"},{"@type":"BreadcrumbList","@id":"https:\/\/teguar.com\/eu\/de\/medizinischer-computer-stellt-benutzerfreundlichkeit-in-den-vordergrund\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/teguar.com\/eu\/de\/"},{"@type":"ListItem","position":2,"name":"Medizinischer Computer stellt Benutzerfreundlichkeit in den Vordergrund"}]},{"@type":"WebSite","@id":"https:\/\/teguar.com\/eu\/en\/#website","url":"https:\/\/teguar.com\/eu\/en\/","name":"Teguar","description":"Industrial PCs, Medical Computers, and Rugged Tablets","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/teguar.com\/eu\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/teguar.com\/eu\/en\/#\/schema\/person\/8656a31ca77439553397cd30c0b308f6","name":"Teguar Computers","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/5fdee48d23c69713cc8714619cf115c768223bda2d66e69d27baa6a0aacb67e7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5fdee48d23c69713cc8714619cf115c768223bda2d66e69d27baa6a0aacb67e7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5fdee48d23c69713cc8714619cf115c768223bda2d66e69d27baa6a0aacb67e7?s=96&d=mm&r=g","caption":"Teguar Computers"},"url":"https:\/\/teguar.com\/eu\/de\/author\/teguarcomputers\/"}]}},"_links":{"self":[{"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/posts\/2244273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/comments?post=2244273"}],"version-history":[{"count":1,"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/posts\/2244273\/revisions"}],"predecessor-version":[{"id":2244277,"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/posts\/2244273\/revisions\/2244277"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/media\/2244275"}],"wp:attachment":[{"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/media?parent=2244273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/categories?post=2244273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/tags?post=2244273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}