{"id":2244222,"date":"2012-10-01T10:00:00","date_gmt":"2012-10-01T10:00:00","guid":{"rendered":"https:\/\/teguar.com\/eu\/215-widescreen-all-in-one-pc-fuer-medizinische-zwecke-jetzt-verfuegbar\/"},"modified":"2025-11-06T19:13:14","modified_gmt":"2025-11-06T19:13:14","slug":"215-widescreen-all-in-one-pc-fuer-medizinische-zwecke-jetzt-verfuegbar","status":"publish","type":"post","link":"https:\/\/teguar.com\/eu\/de\/215-widescreen-all-in-one-pc-fuer-medizinische-zwecke-jetzt-verfuegbar\/","title":{"rendered":"21,5&#8243; Widescreen All-in-One PC f\u00fcr medizinische Zwecke jetzt verf\u00fcgbar"},"content":{"rendered":"\n<p><img decoding=\"async\" alt=\"Medizinischer Computer Teguar\" src=\"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/medical-computer.jpg\" style=\"float:right;padding:10px\"\/>Der neue T-226 21,5\u2033 <a href=\"https:\/\/teguar.com\/eu\/medical-grade-computer\/\">Medical PC<\/a> von Teguar besticht durch sein reinwei\u00dfes \u00c4u\u00dferes und seine geschwungenen Linien, die garantiert jedem Benutzer gefallen werden. Derzeit gibt es f\u00fcr medizinische Plattformen eine breite Palette von Anwendungen, die vom Infotainment am Krankenbett \u00fcber eine WiFi-f\u00e4hige Workstation f\u00fcr Krankenschwestern bis hin zu einer hochaufl\u00f6senden Plattform f\u00fcr medizinische Bildgebung reichen. J\u00fcngste Fortschritte bei medizinischen PCs, wie dem T-226, haben dazu beigetragen, die Nachfrage nach hochaufl\u00f6senden Bildschirmen f\u00fcr Einsatzorte wie den Operationssaal zu befriedigen. Wenn der T-226 am Krankenbett eingesetzt wird, erleichtert der Bildschirm die Kommunikation zwischen Patient und Arzt und hilft dabei, den Patienten \u00fcber seine eigene Diagnose und die Schritte zu seiner Heilung zu informieren. In der gleichen Einheit kann er f\u00fcr Unterhaltung sorgen und eine ansonsten sterile und kalte Umgebung auflockern.    <\/p>\n\n<p>Der T-226 Medical Grade PC ist mit Intel Core i3\/i5\/i7 CPUs f\u00fcr eine deutlich verbesserte Leistung erh\u00e4ltlich. Es k\u00f6nnen bis zu 8 GB DDR3 1066\/1333 Arbeitsspeicher installiert werden, wobei zwei 2,5\u2033 SATA-Festplatten zum Einsatz kommen. Bei Bedarf kann auch eine SSD installiert werden, falls gew\u00fcnscht. Im Vergleich zu medizinischen PC-Produkten der Konkurrenz verf\u00fcgt der T-226 \u00fcber zwei Mini-PCI-e-Steckpl\u00e4tze f\u00fcr eine bessere Erweiterbarkeit. Die vier USB-Steckpl\u00e4tze sind eine durchdachte L\u00f6sung, um die Bed\u00fcrfnisse der Benutzer besser zu erf\u00fcllen.    <\/p>\n\n<p>Das nahtlose Design der Frontabdeckung verhindert, dass Staub und Lebensmittelpartikel in die Schlitze fallen, in denen Bakterien wachsen und Sekund\u00e4rinfektionen beim Patienten verursachen k\u00f6nnen. Das Geh\u00e4use des T-226 ist aus PC+ABS-Kunststoff gefertigt, der eine antibakterielle Nanoformel enth\u00e4lt. Das Verfahren verleiht dem Kunststoffgeh\u00e4use antibakterielle Eigenschaften, die auch durch st\u00e4ndiges Reinigen mit Alkohol nicht abgebaut werden. Das Geh\u00e4use kann sogar \u00fcber 95% der MSRA-Bakterien unterdr\u00fccken.   <\/p>\n\n<p><img decoding=\"async\" alt=\"Teguar medizinische Computer R&#xFC;ckwand\" src=\"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/medical-computer-back-panel.jpg\" style=\"float:left;padding:10px\"\/>Der T-226 Medical Grade Computer hat die europ\u00e4ische\/US-Zertifizierung 60601-1 3rd Edition (EN 60601-1:2006, ANSI\/AAMI ES60601-1:2005, CAN\/CSA C22.2 No. 60601-1:08) erhalten.<\/p>\n\n<p>Die hintere Abdeckung des T-226 Medical PC ist mit einem ger\u00e4uscharmen L\u00fcfter ausgestattet, der eine hervorragende K\u00fchlleistung und einen Ger\u00e4uschpegel von weniger als 30 dB bietet, so dass die Patienten auch bei der Verwendung am Bett Ruhe haben.<\/p>\n\n<hr class=\"wp-block-separator\"\/>\n\n<p>F\u00fcr weitere Produktinformationen klicken Sie bitte hier und\/oder kontaktieren Sie das Teguar Sales Team unter <a href=\"&#109;&#x61;&#105;&#x6c;&#116;&#x6f;&#58;&#x73;&#97;&#x6c;&#101;&#x73;&#64;&#x74;&#101;&#x67;&#117;&#x61;&#114;&#x2e;&#99;&#x6f;&#109;\">&#x73;&#x61;&#108;&#101;s&#64;&#x74;&#x65;&#x67;&#117;ar.&#x63;&#x6f;&#x6d;.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der neue T-226 21,5\u2033 Medical PC von Teguar besticht durch sein reinwei\u00dfes \u00c4u\u00dferes und seine geschwungenen Linien, die garantiert jedem Benutzer gefallen werden. Derzeit gibt es f\u00fcr medizinische Plattformen eine breite Palette von Anwendungen, die vom Infotainment am Krankenbett \u00fcber eine WiFi-f\u00e4hige Workstation f\u00fcr Krankenschwestern bis hin zu einer hochaufl\u00f6senden Plattform f\u00fcr medizinische Bildgebung reichen. [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":2244224,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2809],"tags":[2930,2881,2863,2882,2883],"class_list":["post-2244222","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-produktankundigungen","tag-antimikrobieller-computer","tag-iec-60601-1-2","tag-medizinischer-computer","tag-medizinischer-touchscreen","tag-wi-fi"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.8 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>21,5&quot; Widescreen All-in-One PC f\u00fcr medizinische Zwecke jetzt verf\u00fcgbar<\/title>\n<meta name=\"description\" content=\"Das Geh\u00e4use des T-226 besteht aus PC+ABS-Kunststoff, der eine antibakterielle Nanoformel enth\u00e4lt. Das Verfahren verleiht dem Kunststoffgeh\u00e4use antibakterielle Eigenschaften, die auch durch st\u00e4ndiges Reinigen mit Alkohol nicht abgebaut werden.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/teguar.com\/eu\/de\/215-widescreen-all-in-one-pc-fuer-medizinische-zwecke-jetzt-verfuegbar\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"21,5&quot; Widescreen All-in-One PC f\u00fcr medizinische Zwecke jetzt verf\u00fcgbar\" \/>\n<meta property=\"og:description\" content=\"Das Geh\u00e4use des T-226 besteht aus PC+ABS-Kunststoff, der eine antibakterielle Nanoformel enth\u00e4lt. Das Verfahren verleiht dem Kunststoffgeh\u00e4use antibakterielle Eigenschaften, die auch durch st\u00e4ndiges Reinigen mit Alkohol nicht abgebaut werden.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/teguar.com\/eu\/de\/215-widescreen-all-in-one-pc-fuer-medizinische-zwecke-jetzt-verfuegbar\/\" \/>\n<meta property=\"og:site_name\" content=\"Teguar\" \/>\n<meta property=\"article:published_time\" content=\"2012-10-01T10:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-06T19:13:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/medical-computer-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"350\" \/>\n\t<meta property=\"og:image:height\" content=\"389\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Teguar Computers\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Teguar Computers\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/teguar.com\/eu\/de\/215-widescreen-all-in-one-pc-fuer-medizinische-zwecke-jetzt-verfuegbar\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/teguar.com\/eu\/de\/215-widescreen-all-in-one-pc-fuer-medizinische-zwecke-jetzt-verfuegbar\/\"},\"author\":{\"name\":\"Teguar Computers\",\"@id\":\"https:\/\/teguar.com\/eu\/en\/#\/schema\/person\/8656a31ca77439553397cd30c0b308f6\"},\"headline\":\"21,5&#8243; Widescreen All-in-One PC f\u00fcr medizinische Zwecke jetzt verf\u00fcgbar\",\"datePublished\":\"2012-10-01T10:00:00+00:00\",\"dateModified\":\"2025-11-06T19:13:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/teguar.com\/eu\/de\/215-widescreen-all-in-one-pc-fuer-medizinische-zwecke-jetzt-verfuegbar\/\"},\"wordCount\":392,\"image\":{\"@id\":\"https:\/\/teguar.com\/eu\/de\/215-widescreen-all-in-one-pc-fuer-medizinische-zwecke-jetzt-verfuegbar\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/medical-computer-1.jpg\",\"keywords\":[\"Antimikrobieller Computer\",\"IEC 60601-1-2\",\"medizinischer Computer\",\"Medizinischer Touchscreen\",\"Wi-Fi\"],\"articleSection\":[\"Produkt-Ank\u00fcndigungen\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/teguar.com\/eu\/de\/215-widescreen-all-in-one-pc-fuer-medizinische-zwecke-jetzt-verfuegbar\/\",\"url\":\"https:\/\/teguar.com\/eu\/de\/215-widescreen-all-in-one-pc-fuer-medizinische-zwecke-jetzt-verfuegbar\/\",\"name\":\"21,5\\\" Widescreen All-in-One PC f\u00fcr medizinische Zwecke jetzt verf\u00fcgbar\",\"isPartOf\":{\"@id\":\"https:\/\/teguar.com\/eu\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/teguar.com\/eu\/de\/215-widescreen-all-in-one-pc-fuer-medizinische-zwecke-jetzt-verfuegbar\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/teguar.com\/eu\/de\/215-widescreen-all-in-one-pc-fuer-medizinische-zwecke-jetzt-verfuegbar\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/medical-computer-1.jpg\",\"datePublished\":\"2012-10-01T10:00:00+00:00\",\"dateModified\":\"2025-11-06T19:13:14+00:00\",\"author\":{\"@id\":\"https:\/\/teguar.com\/eu\/en\/#\/schema\/person\/8656a31ca77439553397cd30c0b308f6\"},\"description\":\"Das Geh\u00e4use des T-226 besteht aus PC+ABS-Kunststoff, der eine antibakterielle Nanoformel enth\u00e4lt. Das Verfahren verleiht dem Kunststoffgeh\u00e4use antibakterielle Eigenschaften, die auch durch st\u00e4ndiges Reinigen mit Alkohol nicht abgebaut werden.\",\"breadcrumb\":{\"@id\":\"https:\/\/teguar.com\/eu\/de\/215-widescreen-all-in-one-pc-fuer-medizinische-zwecke-jetzt-verfuegbar\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/teguar.com\/eu\/de\/215-widescreen-all-in-one-pc-fuer-medizinische-zwecke-jetzt-verfuegbar\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/teguar.com\/eu\/de\/215-widescreen-all-in-one-pc-fuer-medizinische-zwecke-jetzt-verfuegbar\/#primaryimage\",\"url\":\"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/medical-computer-1.jpg\",\"contentUrl\":\"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/medical-computer-1.jpg\",\"width\":350,\"height\":389,\"caption\":\"Teguar medical computer\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/teguar.com\/eu\/de\/215-widescreen-all-in-one-pc-fuer-medizinische-zwecke-jetzt-verfuegbar\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/teguar.com\/eu\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"21,5&#8243; Widescreen All-in-One PC f\u00fcr medizinische Zwecke jetzt verf\u00fcgbar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/teguar.com\/eu\/en\/#website\",\"url\":\"https:\/\/teguar.com\/eu\/en\/\",\"name\":\"Teguar\",\"description\":\"Industrial PCs, Medical Computers, and Rugged Tablets\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/teguar.com\/eu\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/teguar.com\/eu\/en\/#\/schema\/person\/8656a31ca77439553397cd30c0b308f6\",\"name\":\"Teguar Computers\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/5fdee48d23c69713cc8714619cf115c768223bda2d66e69d27baa6a0aacb67e7?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5fdee48d23c69713cc8714619cf115c768223bda2d66e69d27baa6a0aacb67e7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5fdee48d23c69713cc8714619cf115c768223bda2d66e69d27baa6a0aacb67e7?s=96&d=mm&r=g\",\"caption\":\"Teguar Computers\"},\"url\":\"https:\/\/teguar.com\/eu\/de\/author\/teguarcomputers\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"21,5\" Widescreen All-in-One PC f\u00fcr medizinische Zwecke jetzt verf\u00fcgbar","description":"Das Geh\u00e4use des T-226 besteht aus PC+ABS-Kunststoff, der eine antibakterielle Nanoformel enth\u00e4lt. Das Verfahren verleiht dem Kunststoffgeh\u00e4use antibakterielle Eigenschaften, die auch durch st\u00e4ndiges Reinigen mit Alkohol nicht abgebaut werden.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/teguar.com\/eu\/de\/215-widescreen-all-in-one-pc-fuer-medizinische-zwecke-jetzt-verfuegbar\/","og_locale":"de_DE","og_type":"article","og_title":"21,5\" Widescreen All-in-One PC f\u00fcr medizinische Zwecke jetzt verf\u00fcgbar","og_description":"Das Geh\u00e4use des T-226 besteht aus PC+ABS-Kunststoff, der eine antibakterielle Nanoformel enth\u00e4lt. Das Verfahren verleiht dem Kunststoffgeh\u00e4use antibakterielle Eigenschaften, die auch durch st\u00e4ndiges Reinigen mit Alkohol nicht abgebaut werden.","og_url":"https:\/\/teguar.com\/eu\/de\/215-widescreen-all-in-one-pc-fuer-medizinische-zwecke-jetzt-verfuegbar\/","og_site_name":"Teguar","article_published_time":"2012-10-01T10:00:00+00:00","article_modified_time":"2025-11-06T19:13:14+00:00","og_image":[{"width":350,"height":389,"url":"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/medical-computer-1.jpg","type":"image\/jpeg"}],"author":"Teguar Computers","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Teguar Computers","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/teguar.com\/eu\/de\/215-widescreen-all-in-one-pc-fuer-medizinische-zwecke-jetzt-verfuegbar\/#article","isPartOf":{"@id":"https:\/\/teguar.com\/eu\/de\/215-widescreen-all-in-one-pc-fuer-medizinische-zwecke-jetzt-verfuegbar\/"},"author":{"name":"Teguar Computers","@id":"https:\/\/teguar.com\/eu\/en\/#\/schema\/person\/8656a31ca77439553397cd30c0b308f6"},"headline":"21,5&#8243; Widescreen All-in-One PC f\u00fcr medizinische Zwecke jetzt verf\u00fcgbar","datePublished":"2012-10-01T10:00:00+00:00","dateModified":"2025-11-06T19:13:14+00:00","mainEntityOfPage":{"@id":"https:\/\/teguar.com\/eu\/de\/215-widescreen-all-in-one-pc-fuer-medizinische-zwecke-jetzt-verfuegbar\/"},"wordCount":392,"image":{"@id":"https:\/\/teguar.com\/eu\/de\/215-widescreen-all-in-one-pc-fuer-medizinische-zwecke-jetzt-verfuegbar\/#primaryimage"},"thumbnailUrl":"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/medical-computer-1.jpg","keywords":["Antimikrobieller Computer","IEC 60601-1-2","medizinischer Computer","Medizinischer Touchscreen","Wi-Fi"],"articleSection":["Produkt-Ank\u00fcndigungen"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/teguar.com\/eu\/de\/215-widescreen-all-in-one-pc-fuer-medizinische-zwecke-jetzt-verfuegbar\/","url":"https:\/\/teguar.com\/eu\/de\/215-widescreen-all-in-one-pc-fuer-medizinische-zwecke-jetzt-verfuegbar\/","name":"21,5\" Widescreen All-in-One PC f\u00fcr medizinische Zwecke jetzt verf\u00fcgbar","isPartOf":{"@id":"https:\/\/teguar.com\/eu\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/teguar.com\/eu\/de\/215-widescreen-all-in-one-pc-fuer-medizinische-zwecke-jetzt-verfuegbar\/#primaryimage"},"image":{"@id":"https:\/\/teguar.com\/eu\/de\/215-widescreen-all-in-one-pc-fuer-medizinische-zwecke-jetzt-verfuegbar\/#primaryimage"},"thumbnailUrl":"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/medical-computer-1.jpg","datePublished":"2012-10-01T10:00:00+00:00","dateModified":"2025-11-06T19:13:14+00:00","author":{"@id":"https:\/\/teguar.com\/eu\/en\/#\/schema\/person\/8656a31ca77439553397cd30c0b308f6"},"description":"Das Geh\u00e4use des T-226 besteht aus PC+ABS-Kunststoff, der eine antibakterielle Nanoformel enth\u00e4lt. Das Verfahren verleiht dem Kunststoffgeh\u00e4use antibakterielle Eigenschaften, die auch durch st\u00e4ndiges Reinigen mit Alkohol nicht abgebaut werden.","breadcrumb":{"@id":"https:\/\/teguar.com\/eu\/de\/215-widescreen-all-in-one-pc-fuer-medizinische-zwecke-jetzt-verfuegbar\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/teguar.com\/eu\/de\/215-widescreen-all-in-one-pc-fuer-medizinische-zwecke-jetzt-verfuegbar\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/teguar.com\/eu\/de\/215-widescreen-all-in-one-pc-fuer-medizinische-zwecke-jetzt-verfuegbar\/#primaryimage","url":"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/medical-computer-1.jpg","contentUrl":"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/medical-computer-1.jpg","width":350,"height":389,"caption":"Teguar medical computer"},{"@type":"BreadcrumbList","@id":"https:\/\/teguar.com\/eu\/de\/215-widescreen-all-in-one-pc-fuer-medizinische-zwecke-jetzt-verfuegbar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/teguar.com\/eu\/de\/"},{"@type":"ListItem","position":2,"name":"21,5&#8243; Widescreen All-in-One PC f\u00fcr medizinische Zwecke jetzt verf\u00fcgbar"}]},{"@type":"WebSite","@id":"https:\/\/teguar.com\/eu\/en\/#website","url":"https:\/\/teguar.com\/eu\/en\/","name":"Teguar","description":"Industrial PCs, Medical Computers, and Rugged Tablets","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/teguar.com\/eu\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/teguar.com\/eu\/en\/#\/schema\/person\/8656a31ca77439553397cd30c0b308f6","name":"Teguar Computers","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/5fdee48d23c69713cc8714619cf115c768223bda2d66e69d27baa6a0aacb67e7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5fdee48d23c69713cc8714619cf115c768223bda2d66e69d27baa6a0aacb67e7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5fdee48d23c69713cc8714619cf115c768223bda2d66e69d27baa6a0aacb67e7?s=96&d=mm&r=g","caption":"Teguar Computers"},"url":"https:\/\/teguar.com\/eu\/de\/author\/teguarcomputers\/"}]}},"_links":{"self":[{"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/posts\/2244222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/comments?post=2244222"}],"version-history":[{"count":1,"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/posts\/2244222\/revisions"}],"predecessor-version":[{"id":2244226,"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/posts\/2244222\/revisions\/2244226"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/media\/2244224"}],"wp:attachment":[{"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/media?parent=2244222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/categories?post=2244222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/tags?post=2244222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}