{"id":2244216,"date":"2012-09-01T10:00:00","date_gmt":"2012-09-01T10:00:00","guid":{"rendered":"https:\/\/teguar.com\/eu\/teguar-laesst-ihren-tablet-traum-wahr-werden\/"},"modified":"2025-11-06T19:13:15","modified_gmt":"2025-11-06T19:13:15","slug":"teguar-laesst-ihren-tablet-traum-wahr-werden","status":"publish","type":"post","link":"https:\/\/teguar.com\/eu\/de\/teguar-laesst-ihren-tablet-traum-wahr-werden\/","title":{"rendered":"Teguar l\u00e4sst Ihren Tablet-Traum wahr werden"},"content":{"rendered":"\n<p>Wenn Sie schon immer von einem robusten Tablet PC getr\u00e4umt haben: leicht, einfach zu transportieren, wasser- und staubdicht und dennoch in der Lage, das g\u00e4ngige Betriebssystem Windows auszuf\u00fchren, sind Ihre Tr\u00e4ume wahr geworden. Das TMT-Pad von Teguar PC bietet eine hochwertige CPU f\u00fcr maximale Leistung, die f\u00fcr die t\u00e4gliche Arbeit im Beruf wichtig ist. Ja, der 9,7&#8243; TMT-Pad PC von Teguar erweckt die Fantasie zum Leben!  <\/p>\n\n<p>Nicht nur auf dem Verbrauchermarkt, sondern auch im industriellen und medizinischen Bereich w\u00e4chst der Trend zu Tablet-Computern schnell. Der industrielle und medizinische Tablet PC von Teguar unterst\u00fctzt das Betriebssystem Windows Embedded 7 und wird auch das in K\u00fcrze erscheinende Windows 8 unterst\u00fctzen. Das Teguar TMT-Pad bietet eine alternative L\u00f6sung f\u00fcr diejenigen, die zwischen dem allgemeinen Verbrauchermarkt und extrem robusten Anwendungen, insbesondere in industriellen und medizinischen Umgebungen, liegen.  <\/p>\n\n<p>Im Vergleich zu einem Tablet PC f\u00fcr Endverbraucher ist das TMT-Pad nach IP54 zertifiziert, d.h. es ist staub- und spritzwassergesch\u00fctzt und \u00fcbersteht einen Fall aus 3 Metern H\u00f6he, ohne Schaden zu nehmen. Diese beiden Eigenschaften unterst\u00fctzen die h\u00f6heren Umweltanforderungen im kommerziellen und medizinischen Bereich. F\u00fcr Benutzer, die keine h\u00f6heren Anforderungen an die Widerstandsf\u00e4higkeit wie z.B. den Milit\u00e4rstandard ben\u00f6tigen, ist das 9,7&#8243; Rugged Tablet viel leichter und tragbarer als herk\u00f6mmliche Rugged Tablet PCs. Dar\u00fcber hinaus ist das TMT-Pad von der europ\u00e4ischen medizinischen Zertifizierung EN60601-1-1 &amp; EN60601-1-2 zugelassen, was es zu einem perfekten mobilen klinischen Assistenten im medizinischen Bereich macht.    <\/p>\n\n<p>Das TMT-Pad wurde f\u00fcr die professionelle Arbeit entwickelt und arbeitet mit Windows Embedded 7 auf einem Intel Atom N2600 Dual-Core-Prozessor. Drahtlose Ger\u00e4te wie Bluetooth, Wi-Fi und optional 3G und GPS machen die Kommunikation mit anderen m\u00f6glich und einfach. Was die Ein- und Ausg\u00e4nge betrifft, so verf\u00fcgt das 9,7&#8243; TPC neben einem einfachen Micro-In\/Line-Out \u00fcber einen USB- und einen LAN- oder HDMI-Anschluss. Au\u00dferdem gibt es eine programmierbare Funktionstaste, die flexibel an die Anforderungen des Benutzers angepasst werden kann.   <\/p>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/TMT-Pad_1_.jpg\" alt=\"Verschiedene robuste Tablet-Anwendungen\" class=\"wp-image-10509\"\/><\/figure>\n\n<h3 class=\"wp-block-heading\"><strong>Anwendungen<\/strong><\/h3>\n\n<p>Teguar bietet verschiedene Zubeh\u00f6rteile f\u00fcr das TMT-Pad an, um verschiedene Anwendungsbereiche wie Bildung, Logistik, Einzelhandel, Medizin, Gewerbe und \u00f6ffentliche Einrichtungen zu bedienen. Lehrer k\u00f6nnen das TMT-Pad zum Beispiel als Lehrmittel im Unterricht einsetzen. Der kapazitive Stift erm\u00f6glicht ihnen die freie Interaktion mit ihren Sch\u00fclern. <\/p>\n\n<p>Und dank der Zertifizierung nach EN60601-1-1&amp;EN60601-1-2 k\u00f6nnen \u00c4rzte und Krankenschwestern die Patientenakte \u00fcber das 9,7-Zoll-Ger\u00e4t lesen, ohne dass es zu elektrischen Interferenzen mit den vielen anderen im medizinischen Bereich verwendeten Ger\u00e4ten kommt.<\/p>\n\n<h3 class=\"wp-block-heading\"><strong>Tablet PC-Anwendungen<\/strong><\/h3>\n\n<p>Das TMT-PAD, ein robuster Tablet PC, ist jetzt erh\u00e4ltlich. F\u00fcr weitere Informationen wenden Sie sich bitte an das Teguar-Vertriebsteam unter <a href=\"m&#x61;&#x69;l&#116;&#x6f;&#x3a;S&#97;&#x6c;es&#x40;&#x54;e&#103;&#x75;ar&#x2e;&#x63;o&#109;\">Sales&#64;Teguar.&#99;&#111;&#109;,<\/a> rufen Sie unter 1 800 870 7715 an oder besuchen Sie die Teguar-Website unter <a href=\"https:\/\/teguar.com\/eu\/\">https:\/\/teguar.com\/eu\/<\/a>. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wenn Sie schon immer von einem robusten Tablet PC getr\u00e4umt haben: leicht, einfach zu transportieren, wasser- und staubdicht und dennoch in der Lage, das g\u00e4ngige Betriebssystem Windows auszuf\u00fchren, sind Ihre Tr\u00e4ume wahr geworden. Das TMT-Pad von Teguar PC bietet eine hochwertige CPU f\u00fcr maximale Leistung, die f\u00fcr die t\u00e4gliche Arbeit im Beruf wichtig ist. Ja, [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":2244218,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2810],"tags":[2919,2881,2885,2864,2929],"class_list":["post-2244216","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-technische-artikel-branchentrends","tag-eingange-und-ausgange","tag-iec-60601-1-2","tag-medizinische-tabletten","tag-robustes-tablet","tag-windows"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.8 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Teguar Computers l\u00e4sst Ihren Tablet-Traum wahr werden<\/title>\n<meta name=\"description\" content=\"Dieses Tablet ist staub- und spritzwassergesch\u00fctzt und eignet sich ideal f\u00fcr industrielle und medizinische Umgebungen. Es unterst\u00fctzt auch Windows.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/teguar.com\/eu\/de\/teguar-laesst-ihren-tablet-traum-wahr-werden\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Teguar l\u00e4sst Ihren Tablet-Traum wahr werden\" \/>\n<meta property=\"og:description\" content=\"Dieses Tablet ist staub- und spritzwassergesch\u00fctzt und eignet sich ideal f\u00fcr industrielle und medizinische Umgebungen. Es unterst\u00fctzt auch Windows.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/teguar.com\/eu\/de\/teguar-laesst-ihren-tablet-traum-wahr-werden\/\" \/>\n<meta property=\"og:site_name\" content=\"Teguar\" \/>\n<meta property=\"article:published_time\" content=\"2012-09-01T10:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-06T19:13:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/TMT-Pad_1_-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Teguar Computers\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Teguar Computers\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/teguar.com\/eu\/de\/teguar-laesst-ihren-tablet-traum-wahr-werden\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/teguar.com\/eu\/de\/teguar-laesst-ihren-tablet-traum-wahr-werden\/\"},\"author\":{\"name\":\"Teguar Computers\",\"@id\":\"https:\/\/teguar.com\/eu\/en\/#\/schema\/person\/8656a31ca77439553397cd30c0b308f6\"},\"headline\":\"Teguar l\u00e4sst Ihren Tablet-Traum wahr werden\",\"datePublished\":\"2012-09-01T10:00:00+00:00\",\"dateModified\":\"2025-11-06T19:13:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/teguar.com\/eu\/de\/teguar-laesst-ihren-tablet-traum-wahr-werden\/\"},\"wordCount\":479,\"image\":{\"@id\":\"https:\/\/teguar.com\/eu\/de\/teguar-laesst-ihren-tablet-traum-wahr-werden\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/TMT-Pad_1_-1.jpg\",\"keywords\":[\"Eing\u00e4nge und Ausg\u00e4nge\",\"IEC 60601-1-2\",\"medizinische Tabletten\",\"Robustes Tablet\",\"Windows\"],\"articleSection\":[\"Technische Artikel &amp; Branchentrends\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/teguar.com\/eu\/de\/teguar-laesst-ihren-tablet-traum-wahr-werden\/\",\"url\":\"https:\/\/teguar.com\/eu\/de\/teguar-laesst-ihren-tablet-traum-wahr-werden\/\",\"name\":\"Teguar Computers l\u00e4sst Ihren Tablet-Traum wahr werden\",\"isPartOf\":{\"@id\":\"https:\/\/teguar.com\/eu\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/teguar.com\/eu\/de\/teguar-laesst-ihren-tablet-traum-wahr-werden\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/teguar.com\/eu\/de\/teguar-laesst-ihren-tablet-traum-wahr-werden\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/TMT-Pad_1_-1.jpg\",\"datePublished\":\"2012-09-01T10:00:00+00:00\",\"dateModified\":\"2025-11-06T19:13:15+00:00\",\"author\":{\"@id\":\"https:\/\/teguar.com\/eu\/en\/#\/schema\/person\/8656a31ca77439553397cd30c0b308f6\"},\"description\":\"Dieses Tablet ist staub- und spritzwassergesch\u00fctzt und eignet sich ideal f\u00fcr industrielle und medizinische Umgebungen. Es unterst\u00fctzt auch Windows.\",\"breadcrumb\":{\"@id\":\"https:\/\/teguar.com\/eu\/de\/teguar-laesst-ihren-tablet-traum-wahr-werden\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/teguar.com\/eu\/de\/teguar-laesst-ihren-tablet-traum-wahr-werden\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/teguar.com\/eu\/de\/teguar-laesst-ihren-tablet-traum-wahr-werden\/#primaryimage\",\"url\":\"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/TMT-Pad_1_-1.jpg\",\"contentUrl\":\"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/TMT-Pad_1_-1.jpg\",\"width\":620,\"height\":300,\"caption\":\"Various rugged tablet applications\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/teguar.com\/eu\/de\/teguar-laesst-ihren-tablet-traum-wahr-werden\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/teguar.com\/eu\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Teguar l\u00e4sst Ihren Tablet-Traum wahr werden\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/teguar.com\/eu\/en\/#website\",\"url\":\"https:\/\/teguar.com\/eu\/en\/\",\"name\":\"Teguar\",\"description\":\"Industrial PCs, Medical Computers, and Rugged Tablets\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/teguar.com\/eu\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/teguar.com\/eu\/en\/#\/schema\/person\/8656a31ca77439553397cd30c0b308f6\",\"name\":\"Teguar Computers\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/5fdee48d23c69713cc8714619cf115c768223bda2d66e69d27baa6a0aacb67e7?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5fdee48d23c69713cc8714619cf115c768223bda2d66e69d27baa6a0aacb67e7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5fdee48d23c69713cc8714619cf115c768223bda2d66e69d27baa6a0aacb67e7?s=96&d=mm&r=g\",\"caption\":\"Teguar Computers\"},\"url\":\"https:\/\/teguar.com\/eu\/de\/author\/teguarcomputers\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Teguar Computers l\u00e4sst Ihren Tablet-Traum wahr werden","description":"Dieses Tablet ist staub- und spritzwassergesch\u00fctzt und eignet sich ideal f\u00fcr industrielle und medizinische Umgebungen. Es unterst\u00fctzt auch Windows.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/teguar.com\/eu\/de\/teguar-laesst-ihren-tablet-traum-wahr-werden\/","og_locale":"de_DE","og_type":"article","og_title":"Teguar l\u00e4sst Ihren Tablet-Traum wahr werden","og_description":"Dieses Tablet ist staub- und spritzwassergesch\u00fctzt und eignet sich ideal f\u00fcr industrielle und medizinische Umgebungen. Es unterst\u00fctzt auch Windows.","og_url":"https:\/\/teguar.com\/eu\/de\/teguar-laesst-ihren-tablet-traum-wahr-werden\/","og_site_name":"Teguar","article_published_time":"2012-09-01T10:00:00+00:00","article_modified_time":"2025-11-06T19:13:15+00:00","og_image":[{"width":620,"height":300,"url":"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/TMT-Pad_1_-1.jpg","type":"image\/jpeg"}],"author":"Teguar Computers","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Teguar Computers","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/teguar.com\/eu\/de\/teguar-laesst-ihren-tablet-traum-wahr-werden\/#article","isPartOf":{"@id":"https:\/\/teguar.com\/eu\/de\/teguar-laesst-ihren-tablet-traum-wahr-werden\/"},"author":{"name":"Teguar Computers","@id":"https:\/\/teguar.com\/eu\/en\/#\/schema\/person\/8656a31ca77439553397cd30c0b308f6"},"headline":"Teguar l\u00e4sst Ihren Tablet-Traum wahr werden","datePublished":"2012-09-01T10:00:00+00:00","dateModified":"2025-11-06T19:13:15+00:00","mainEntityOfPage":{"@id":"https:\/\/teguar.com\/eu\/de\/teguar-laesst-ihren-tablet-traum-wahr-werden\/"},"wordCount":479,"image":{"@id":"https:\/\/teguar.com\/eu\/de\/teguar-laesst-ihren-tablet-traum-wahr-werden\/#primaryimage"},"thumbnailUrl":"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/TMT-Pad_1_-1.jpg","keywords":["Eing\u00e4nge und Ausg\u00e4nge","IEC 60601-1-2","medizinische Tabletten","Robustes Tablet","Windows"],"articleSection":["Technische Artikel &amp; Branchentrends"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/teguar.com\/eu\/de\/teguar-laesst-ihren-tablet-traum-wahr-werden\/","url":"https:\/\/teguar.com\/eu\/de\/teguar-laesst-ihren-tablet-traum-wahr-werden\/","name":"Teguar Computers l\u00e4sst Ihren Tablet-Traum wahr werden","isPartOf":{"@id":"https:\/\/teguar.com\/eu\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/teguar.com\/eu\/de\/teguar-laesst-ihren-tablet-traum-wahr-werden\/#primaryimage"},"image":{"@id":"https:\/\/teguar.com\/eu\/de\/teguar-laesst-ihren-tablet-traum-wahr-werden\/#primaryimage"},"thumbnailUrl":"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/TMT-Pad_1_-1.jpg","datePublished":"2012-09-01T10:00:00+00:00","dateModified":"2025-11-06T19:13:15+00:00","author":{"@id":"https:\/\/teguar.com\/eu\/en\/#\/schema\/person\/8656a31ca77439553397cd30c0b308f6"},"description":"Dieses Tablet ist staub- und spritzwassergesch\u00fctzt und eignet sich ideal f\u00fcr industrielle und medizinische Umgebungen. Es unterst\u00fctzt auch Windows.","breadcrumb":{"@id":"https:\/\/teguar.com\/eu\/de\/teguar-laesst-ihren-tablet-traum-wahr-werden\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/teguar.com\/eu\/de\/teguar-laesst-ihren-tablet-traum-wahr-werden\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/teguar.com\/eu\/de\/teguar-laesst-ihren-tablet-traum-wahr-werden\/#primaryimage","url":"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/TMT-Pad_1_-1.jpg","contentUrl":"https:\/\/teguar.com\/eu\/wp-content\/uploads\/sites\/2\/2020\/08\/TMT-Pad_1_-1.jpg","width":620,"height":300,"caption":"Various rugged tablet applications"},{"@type":"BreadcrumbList","@id":"https:\/\/teguar.com\/eu\/de\/teguar-laesst-ihren-tablet-traum-wahr-werden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/teguar.com\/eu\/de\/"},{"@type":"ListItem","position":2,"name":"Teguar l\u00e4sst Ihren Tablet-Traum wahr werden"}]},{"@type":"WebSite","@id":"https:\/\/teguar.com\/eu\/en\/#website","url":"https:\/\/teguar.com\/eu\/en\/","name":"Teguar","description":"Industrial PCs, Medical Computers, and Rugged Tablets","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/teguar.com\/eu\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/teguar.com\/eu\/en\/#\/schema\/person\/8656a31ca77439553397cd30c0b308f6","name":"Teguar Computers","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/5fdee48d23c69713cc8714619cf115c768223bda2d66e69d27baa6a0aacb67e7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5fdee48d23c69713cc8714619cf115c768223bda2d66e69d27baa6a0aacb67e7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5fdee48d23c69713cc8714619cf115c768223bda2d66e69d27baa6a0aacb67e7?s=96&d=mm&r=g","caption":"Teguar Computers"},"url":"https:\/\/teguar.com\/eu\/de\/author\/teguarcomputers\/"}]}},"_links":{"self":[{"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/posts\/2244216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/comments?post=2244216"}],"version-history":[{"count":1,"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/posts\/2244216\/revisions"}],"predecessor-version":[{"id":2244220,"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/posts\/2244216\/revisions\/2244220"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/media\/2244218"}],"wp:attachment":[{"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/media?parent=2244216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/categories?post=2244216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teguar.com\/eu\/de\/wp-json\/wp\/v2\/tags?post=2244216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}